{"id":957626,"date":"2026-05-11T15:52:12","date_gmt":"2026-05-11T14:52:12","guid":{"rendered":"https:\/\/jerichowriters.com\/our-services\/agentmatch\/literary-agency\/edwards-fuglewicz\/"},"modified":"2026-05-11T15:52:12","modified_gmt":"2026-05-11T14:52:12","slug":"edwards-fuglewicz","status":"publish","type":"agency","link":"https:\/\/jerichowriters.com\/our-services\/agentmatch\/literary-agency\/edwards-fuglewicz\/","title":{"rendered":"Edwards Fuglewicz"},"content":{"rendered":"","protected":false},"template":"","meta":{"_acf_changed":false},"class_list":["post-957626","agency","type-agency","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Edwards Fuglewicz , Literary Agency \u2013 Full agent profiles | Jericho Writers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jerichowriters.com\/our-services\/agentmatch\/literary-agency\/edwards-fuglewicz\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Edwards Fuglewicz &#8211; Jericho Writers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jerichowriters.com\/our-services\/agentmatch\/literary-agency\/edwards-fuglewicz\/\" \/>\n<meta property=\"og:site_name\" content=\"Jericho Writers\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jerichowriters\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@JerichoWriters\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jerichowriters.com\\\/our-services\\\/agentmatch\\\/literary-agency\\\/edwards-fuglewicz\\\/\",\"url\":\"https:\\\/\\\/jerichowriters.com\\\/our-services\\\/agentmatch\\\/literary-agency\\\/edwards-fuglewicz\\\/\",\"name\":\"Edwards Fuglewicz &#8211; Jericho Writers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jerichowriters.com\\\/#website\"},\"datePublished\":\"2026-05-11T14:52:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jerichowriters.com\\\/our-services\\\/agentmatch\\\/literary-agency\\\/edwards-fuglewicz\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jerichowriters.com\\\/our-services\\\/agentmatch\\\/literary-agency\\\/edwards-fuglewicz\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jerichowriters.com\\\/our-services\\\/agentmatch\\\/literary-agency\\\/edwards-fuglewicz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jerichowriters.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agencies\",\"item\":\"https:\\\/\\\/jerichowriters.com\\\/our-services\\\/agentmatch\\\/literary-agency\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Edwards Fuglewicz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jerichowriters.com\\\/#website\",\"url\":\"https:\\\/\\\/jerichowriters.com\\\/\",\"name\":\"Jericho Writers\",\"description\":\"Getting you published\",\"publisher\":{\"@id\":\"https:\\\/\\\/jerichowriters.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jerichowriters.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jerichowriters.com\\\/#organization\",\"name\":\"Jericho Writers\",\"url\":\"https:\\\/\\\/jerichowriters.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/jerichowriters.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jerichowriters.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cropped-footer-logo.png\",\"contentUrl\":\"https:\\\/\\\/jerichowriters.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cropped-footer-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Jericho Writers\"},\"image\":{\"@id\":\"https:\\\/\\\/jerichowriters.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jerichowriters\",\"https:\\\/\\\/x.com\\\/JerichoWriters\",\"https:\\\/\\\/www.instagram.com\\\/jerichowriters\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/jericho-writers\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCcs1qhjwLR6bQYDR2x3PbOw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Edwards Fuglewicz , Literary Agency \u2013 Full agent profiles | Jericho Writers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jerichowriters.com\/our-services\/agentmatch\/literary-agency\/edwards-fuglewicz\/","og_locale":"en_GB","og_type":"article","og_title":"Edwards Fuglewicz &#8211; Jericho Writers","og_url":"https:\/\/jerichowriters.com\/our-services\/agentmatch\/literary-agency\/edwards-fuglewicz\/","og_site_name":"Jericho Writers","article_publisher":"https:\/\/www.facebook.com\/jerichowriters","twitter_card":"summary_large_image","twitter_site":"@JerichoWriters","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jerichowriters.com\/our-services\/agentmatch\/literary-agency\/edwards-fuglewicz\/","url":"https:\/\/jerichowriters.com\/our-services\/agentmatch\/literary-agency\/edwards-fuglewicz\/","name":"Edwards Fuglewicz &#8211; Jericho Writers","isPartOf":{"@id":"https:\/\/jerichowriters.com\/#website"},"datePublished":"2026-05-11T14:52:12+00:00","breadcrumb":{"@id":"https:\/\/jerichowriters.com\/our-services\/agentmatch\/literary-agency\/edwards-fuglewicz\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jerichowriters.com\/our-services\/agentmatch\/literary-agency\/edwards-fuglewicz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jerichowriters.com\/our-services\/agentmatch\/literary-agency\/edwards-fuglewicz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jerichowriters.com\/"},{"@type":"ListItem","position":2,"name":"Agencies","item":"https:\/\/jerichowriters.com\/our-services\/agentmatch\/literary-agency\/"},{"@type":"ListItem","position":3,"name":"Edwards Fuglewicz"}]},{"@type":"WebSite","@id":"https:\/\/jerichowriters.com\/#website","url":"https:\/\/jerichowriters.com\/","name":"Jericho Writers","description":"Getting you published","publisher":{"@id":"https:\/\/jerichowriters.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jerichowriters.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/jerichowriters.com\/#organization","name":"Jericho Writers","url":"https:\/\/jerichowriters.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/jerichowriters.com\/#\/schema\/logo\/image\/","url":"https:\/\/jerichowriters.com\/wp-content\/uploads\/2021\/03\/cropped-footer-logo.png","contentUrl":"https:\/\/jerichowriters.com\/wp-content\/uploads\/2021\/03\/cropped-footer-logo.png","width":512,"height":512,"caption":"Jericho Writers"},"image":{"@id":"https:\/\/jerichowriters.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jerichowriters","https:\/\/x.com\/JerichoWriters","https:\/\/www.instagram.com\/jerichowriters\/","https:\/\/www.linkedin.com\/company\/jericho-writers\/","https:\/\/www.youtube.com\/channel\/UCcs1qhjwLR6bQYDR2x3PbOw"]}]}},"_links":{"self":[{"href":"https:\/\/jerichowriters.com\/index.php\/wp-json\/wp\/v2\/agency\/957626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jerichowriters.com\/index.php\/wp-json\/wp\/v2\/agency"}],"about":[{"href":"https:\/\/jerichowriters.com\/index.php\/wp-json\/wp\/v2\/types\/agency"}],"wp:attachment":[{"href":"https:\/\/jerichowriters.com\/index.php\/wp-json\/wp\/v2\/media?parent=957626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}